{"id":7880,"date":"2024-09-19T06:42:00","date_gmt":"2024-09-19T04:42:00","guid":{"rendered":"https:\/\/stiftungsmarktplatz.eu\/blog\/?p=7880"},"modified":"2024-09-19T10:30:17","modified_gmt":"2024-09-19T08:30:17","slug":"stiftungsapero-feiert-premiere-in-basel","status":"publish","type":"post","link":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/","title":{"rendered":"StiftungsAp\u00e9ro feiert Premiere in Basel"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesezeit: <\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">Minuten<\/span><\/span>\n<p><em>Im Rahmen der SommerTour feierte der StiftungsAp\u00e9ro eine weitere Premiere. Erstmals machte der StiftungsAp\u00e9ro in der Schweiz Station, genau gesagt in Basel <a href=\"https:\/\/www.profonds.org\/de\/\" target=\"_blank\" rel=\"noreferrer noopener\">in den R\u00e4umen des Dachverbands gemeinn\u00fctziger Stiftungen der Schweiz<\/a>, kurz profonds. Es war ein StiftungsAp\u00e9ro, bei dem der Klartext zu Gast war, aber eben auch der damit verbundene Gedankenansto\u00df. Nat\u00fcrlich kam auch das StiftungsAp\u00e9ro-typische Essen, Trinken &amp; Reden nicht zu kurz, bei uns weckte der StiftungsAp\u00e9ro sofort die Neugier auf mehr. Denn in der Schweiz ticken vielleicht die Uhren anders, aber die Stiftungsmenschen eint wie hierzulande vor allem Eines: die gute Tat.<\/em><\/p>\n\n\n\n<p>Wir machten uns am Morgen des 4. September mit dem Zug gen Freiburg auf den Weg nach Basel, Deutsche Bahn-typisch wurde der ICE am Bahnhof Basel-Bad angehalten, da der Zug aus Deutschland kommend Versp\u00e4tung aufgebaut hatte. Die Schweizerische SBB geht damit aber konsequent um: Derlei gibt es in der Schweiz nicht, und bevor der Schweizer Fahrplan durch die Deutschen durcheinandergebracht wird, werden deren Z\u00fcge einfach gestoppt. War aber kein Problem, direkt am Parkplatz am Bahnhofsvorplatz wartete Stiftungsberater und -experte Ronald Biehler auf mich. Er holte mich ab und kutschierte uns beide in die Dufourstra\u00dfe, wo die Kanzlei Dufour und eben profonds ihren Sitz haben. In Empfang nahmen uns Susannah Todd, die uns im Vorfeld tatkr\u00e4ftig unterst\u00fctzte, und Dr. Christoph Degen, Chef von profonds und vermutlich (sicherlich) der profundeste Kenner der Schweizerischen Stiftungslandschaft.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote td_quote_box td_box_center is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong><em><u>Ap\u00e9rothek-Tipp:<\/u><\/em><\/strong><em> <\/em><br><em>Alle Eindr\u00fccke von der diesj\u00e4hrigen StiftungsAp\u00e9ro SommerTour bzw. dem, was sich auf den 7 Stationen alles zugetragen hat, <a href=\"https:\/\/stiftungsapero.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">finden Sie auch in der Ap\u00e9rothek<\/a>.<\/em><\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Transparenzregister kann man auch mit anderer Brille sehen<\/h2>\n\n\n\n<p>In seinem Impuls gab Dr. Christoph Degen dann einen sehr eindr\u00fccklichen wie kompakten Eindruck zu dem, <a href=\"https:\/\/stiftungsmarktplatz.eu\/blog\/viele-in-der-bevoelkerung-wissen-gar-nicht-was-stiftungen-alles-leisten\/\" target=\"_blank\" rel=\"noreferrer noopener\">was ihn in seiner t\u00e4glichen Praxis aus Stiftungssicht umtreibt<\/a>. Ein Thema hatte es ihm besonders angetan, und ich muss sagen, dass ich Christoph Degen sehr dankbar war, dass er hier so offen gesprochen hat. F\u00fcr ihn ist das Transparenzregister aus Stiftungssicht zumindest problematisch zu sehen. <\/p>\n\n\n\n<p>Das Transparenzregister, so vern\u00fcnftig ein solches ist, sieht auch f\u00fcr Stiftungen vor, die Beg\u00fcnstigten zu nennen, in einer Datenbank zu f\u00fchren und diese Information auch aktuell zu halten. Dies setzt voraus, dass Beg\u00fcnstigte einer Stiftung benannt werden k\u00f6nnen. Genau hier entsteht das Problem in den Augen von Dr. Christoph Degen. Denn Stiftungen haben ja per se keine Beg\u00fcnstigten, die Regelung, ersatzweise die Gremienverantwortlichen zu benennen, ist schlichtweg nicht zu Ende gedacht worden. Denn wenn es keine Beg\u00fcnstigten im Sinne des Transparenzregisters gibt, ersatzweise dann Gremienmitglieder herangezogen werden m\u00fcssen, werden Stiftungen und deren Verantwortliche quasi zu einer Falschaussage gezwungen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pflichtverletzung ante portas?<\/h2>\n\n\n\n<p>Wer nun als Stiftungsverantwortlicher zu einer Falschaussage gebracht wird, handelt dieser noch zum Wohle der Stiftung? Und wenn er das nicht tut, entsteht dann nicht der Tatbestand der Pflichtverletzung? Diese Fragen brachte Dr. Christoph Degen auf, er konnte auf Basis dessen darlegen, <a href=\"https:\/\/stiftungsmarktplatz.eu\/blog\/alle-geheimnisse-auf-einen-blick\/\" target=\"_blank\" rel=\"noreferrer noopener\">warum es in der Schweiz ein solches Transparenzregister nicht gibt<\/a>. Dies wiederum brachte uns in der Diskussion zu der Frage, warum wir Deutschen in vorauseilendem Gehorsam direkt mal ein Transparenzregister eingerichtet haben, den Stiftungen damit eine Aufgabe aufgeb\u00fcrdet haben, die f\u00fcr jede einzelne Stiftung Fragen provoziert, die diese eigentlich weder braucht noch beantworten kann. Es war interessant zu h\u00f6ren, dass sich da \u201eThema Transparenzregister\u201c auch anders lesen l\u00e4sst, dass die Frage erlaubt sein muss, ob zwischen Pflichtverletzung auf Stiftungsseite und Ausformung der Beschaffenheit des Transparenzregisters auf Seiten des Gesetzgebers ausreichend abgewogen wurde.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wenn die Prothese aus dem 3D-Drucker kommt\u2026<\/h2>\n\n\n\n<p>Keine zwei Meinungen herrschten zu den anderen beiden Impulsen vor. <a href=\"https:\/\/stiftungsmarktplatz.eu\/dienstleister\/handicap-international\/\" target=\"_blank\" rel=\"noreferrer noopener\">Matthias Renner von Handicap International<\/a> brachte in seinem Impuls noch einmal den Gedankenansto\u00df mit, dass gemeinn\u00fctzige Organisationen zur G\u00e4nze Innovationen in sich tragen k\u00f6nnen, brachte zum Beweis das Beispiel der mit dem 3D-Drucker gefertigten Prothesen mit. <\/p>\n\n\n\n<p>An dieser Technologie arbeitet Handicap International intensiv, macht solch eine Prothese die Arbeit vor Ort doch noch einmal zielf\u00fchrender, aber eben auch ein St\u00fcck weit einfacher. <a href=\"https:\/\/fondsfibel.de\/aquila-capital-infrastructure-fund\/\" target=\"_blank\" rel=\"noreferrer noopener\">Henry Wolter von AQ Investment wiederum formulierte es in seinem Impuls \u00fcber Infrastruktur-Investments im Stiftungsverm\u00f6gen<\/a> so: \u201eStiftungen haben das Diversifikationsgebot vor der Brust. Um das lebendig zu halten, bauen Anlagen etwa in Infrastruktur beispielsweise in Erneuerbare Energien mit ihren besonderen Eigenschaften praktisch jedem Stiftungsverm\u00f6gen gewisserma\u00dfen eine Br\u00fccke.\u201c <\/p>\n\n\n\n<p>Was er meinte und was er auch zum Ausdruck brachte war, dass Diversifizieren im Stiftungsverm\u00f6gen inzwischen sehr breit gefasst m\u00f6glich ist. Es d\u00fcrfte auch immer mehr Stiftungen m\u00f6glich sein, \u00e4hnlich anzulegen wie die gro\u00dfen Endowments in den USA. Daf\u00fcr aber, und da ist sich Henry Wolter sicher, braucht es Alternative Anlagen, denn ohne diese w\u00e4re der Anlageerfolg der Endowments niemals so eingetreten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Drei take aways der StiftungsAp\u00e9ro SommerTour 2024<\/h2>\n\n\n\n<p><a href=\"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-sommertour-2024-die-zweite-woche\/\" target=\"_blank\" rel=\"noreferrer noopener\">Beim StiftungsAp\u00e9ro-typischen Ap\u00e9ro<\/a> dann hatte der Ap\u00e9ro ein Heimspiel. Der Begriff stammt aus der Schweiz, er meint das gesellige Beisammensein nach getaner Arbeit, und genauso nahmen wir das Ganze auch in Angriff \u2013 und nehmen genau diese Erinnerung mit in die Planung der StiftungsAp\u00e9ro WinterTour 2025. <\/p>\n\n\n\n<p>Thematisch nehmen wir drei Thesen aus den sieben Terminen der StiftungsAp\u00e9ro SommerTour mit. 1) Stiftungspraxis ver\u00e4ndert sich momentan, es baut sich Entscheidungsdruck auf, vom \u201eDas haben wir immer so gemacht\u201c abzuweichen. 2) Kommunikation, StoryTelling, Major Donor Marketing sind drei Schlagworte, die Stiftungsverantwortliche k\u00fcnftig mit Inhalt f\u00fcllen m\u00fcssen. Will Stiftung als relevant wahrgenommen werden, muss sie bzw. m\u00fcssen ihre Verantwortlichen diese Disziplinen k\u00f6nnen. 3) Im Stiftungsverm\u00f6gen ist Sorgfalt k\u00fcnftig ein Rahmen, der mit mehr Ingredienzien bef\u00fcllt werden muss. Sorgfalt hei\u00dft Konzept, Sorgfalt hei\u00dft 4Ds (Diversifizieren, Delegieren, Dokumentieren, Durchhalten) \u2013 plus einem f\u00fcnften D: dem Dranbleiben. Stiftungsverm\u00f6gen verlangt kontinuierliches Dranbleiben, erledigt ist die Aufgabe nie, nach der Anlageentscheidung ist vor der Anlageentscheidung.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.meinstiftungsexperte.de\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"535\" src=\"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/03\/stiftungsexperten-handbuch1200x627-1024x535.jpg\" alt=\"Stiftungsexperten-Handbuch\" class=\"wp-image-7060\" srcset=\"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/03\/stiftungsexperten-handbuch1200x627-1024x535.jpg 1024w, https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/03\/stiftungsexperten-handbuch1200x627-300x157.jpg 300w, https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/03\/stiftungsexperten-handbuch1200x627-768x401.jpg 768w, https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/03\/stiftungsexperten-handbuch1200x627-696x364.jpg 696w, https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/03\/stiftungsexperten-handbuch1200x627-1068x558.jpg 1068w, https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/03\/stiftungsexperten-handbuch1200x627.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Zusammengefasst<\/h2>\n\n\n\n<p>Die StiftungsAp\u00e9ro SommerTour 2024 feierte in Basel am 4. September ihren passenden Abschluss. Mit Dr. Christoph Degen, dem Chef von profonds, redete ein Verbandsvertreter Klartext und sprach den Anwesenden aus der (Stiftungs)seele. Stiftungspraxis ver\u00e4ndert sich, weil sich das Stiftungsumfeld ver\u00e4ndert, und dennoch gibt es Grundfesten, die f\u00fcr Stiftungsverantwortliche zeitlos g\u00fcltig sind. <\/p>\n\n\n\n<p>Diese Erkenntnis war so etwas wie die zentrale Mitnahme aus der StiftungsAp\u00e9ro SommerTour, nicht zuletzt, weil die Diskussion um die Rolle von Stiftungen in der Gesellschaft Fahrt aufzunehmen scheint. Wir k\u00f6nnen uns an dieser Stelle nur bei allen Protagonisten der StiftungsAp\u00e9ro SommerTour bedanken, allen Partnern und Begleitern, und nat\u00fcrlich bei den gut 200 G\u00e4sten, die in Dresden, Berlin, Hamburg, Frankfurt, K\u00f6ln, Dortmund und Basel unserer Einladung folgten. DANKE, dass Sie vor Ort waren, und wir sagen es mal mit der \u00f6sterreichischen Schauspiel- und Gouverneurslegende Arnold Schwarzenegger: We will be back, mit der am 21.1.2025 startenden StiftungsAp\u00e9ro WinterTour 2025 (verweisen auf <a href=\"http:\/\/www.stiftungsapero.de\">www.stiftungsapero.de<\/a>). \u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesezeit: <\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">Minuten<\/span><\/span>Im Rahmen der SommerTour feierte der StiftungsAp\u00e9ro eine weitere Premiere. Erstmals machte der StiftungsAp\u00e9ro in der Schweiz Station, genau gesagt in Basel in den R\u00e4umen des Dachverbands gemeinn\u00fctziger Stiftungen der Schweiz, kurz profonds. Es war ein StiftungsAp\u00e9ro, bei dem der Klartext zu Gast war, aber eben auch der damit verbundene Gedankenansto\u00df. Nat\u00fcrlich kam auch das StiftungsAp\u00e9ro-typische Essen, Trinken &#038; Reden nicht zu kurz, bei uns weckte der StiftungsAp\u00e9ro sofort die Neugier auf mehr. Denn in der Schweiz ticken vielleicht die Uhren anders, aber die Stiftungsmenschen eint wie hierzulande vor allem Eines: die gute Tat.<\/p>\n","protected":false},"author":8,"featured_media":7895,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[12],"tags":[145,284,419,27,38,46],"class_list":{"0":"post-7880","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tipps-fuer-die-stiftungspraxis","8":"tag-stiftungskommunikation","9":"tag-stiftungsevent","10":"tag-stiftungsapero","11":"tag-stiftungsvermoegen","12":"tag-transparenzregister","13":"tag-stiftungsnetzwerk"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>StiftungsAp\u00e9ro feiert Premiere in Basel - Der Stiftungsblog f\u00fcr die Stiftungspraxis<\/title>\n<meta name=\"description\" content=\"Im Rahmen der SommerTour feierte der StiftungsAp\u00e9ro eine weitere Premiere. Erstmals machte der StiftungsAp\u00e9ro in der Schweiz Station, genau gesagt in Basel in den R\u00e4umen des Dachverbands gemeinn\u00fctziger Stiftungen der Schweiz, kurz profonds.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"StiftungsAp\u00e9ro feiert Premiere in Basel - Der Stiftungsblog f\u00fcr die Stiftungspraxis\" \/>\n<meta property=\"og:description\" content=\"Im Rahmen der SommerTour feierte der StiftungsAp\u00e9ro eine weitere Premiere. Erstmals machte der StiftungsAp\u00e9ro in der Schweiz Station, genau gesagt in Basel in den R\u00e4umen des Dachverbands gemeinn\u00fctziger Stiftungen der Schweiz, kurz profonds.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/\" \/>\n<meta property=\"og:site_name\" content=\"Der Stiftungsblog f\u00fcr die Stiftungspraxis\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-19T04:42:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-19T08:30:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/09\/Rueckschau-StiftungsApero-SommerTour-FinaIe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tobias Karow\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tobias Karow\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungsapero-feiert-premiere-in-basel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungsapero-feiert-premiere-in-basel\\\/\"},\"author\":{\"name\":\"Tobias Karow\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/person\\\/3a42780bf87a2088578f1e8077ccfa44\"},\"headline\":\"StiftungsAp\u00e9ro feiert Premiere in Basel\",\"datePublished\":\"2024-09-19T04:42:00+00:00\",\"dateModified\":\"2024-09-19T08:30:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungsapero-feiert-premiere-in-basel\\\/\"},\"wordCount\":1135,\"publisher\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungsapero-feiert-premiere-in-basel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Rueckschau-StiftungsApero-SommerTour-FinaIe.jpg\",\"keywords\":[\"Stiftungskommunikation\",\"Stiftungsevent\",\"StiftungsAp\u00e9ro\",\"Stiftungsverm\u00f6gen\",\"Transparenzregister\",\"Stiftungsnetzwerk\"],\"articleSection\":[\"Tipps f\u00fcr die Stiftungspraxis\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungsapero-feiert-premiere-in-basel\\\/\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungsapero-feiert-premiere-in-basel\\\/\",\"name\":\"StiftungsAp\u00e9ro feiert Premiere in Basel - Der Stiftungsblog f\u00fcr die Stiftungspraxis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungsapero-feiert-premiere-in-basel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungsapero-feiert-premiere-in-basel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Rueckschau-StiftungsApero-SommerTour-FinaIe.jpg\",\"datePublished\":\"2024-09-19T04:42:00+00:00\",\"dateModified\":\"2024-09-19T08:30:17+00:00\",\"description\":\"Im Rahmen der SommerTour feierte der StiftungsAp\u00e9ro eine weitere Premiere. Erstmals machte der StiftungsAp\u00e9ro in der Schweiz Station, genau gesagt in Basel in den R\u00e4umen des Dachverbands gemeinn\u00fctziger Stiftungen der Schweiz, kurz profonds.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungsapero-feiert-premiere-in-basel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungsapero-feiert-premiere-in-basel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungsapero-feiert-premiere-in-basel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Rueckschau-StiftungsApero-SommerTour-FinaIe.jpg\",\"contentUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Rueckschau-StiftungsApero-SommerTour-FinaIe.jpg\",\"width\":1200,\"height\":675,\"caption\":\"R\u00fcckschau StiftungsAp\u00e9ro SommerTour FinaIe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungsapero-feiert-premiere-in-basel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"StiftungsAp\u00e9ro feiert Premiere in Basel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/\",\"name\":\"Der Stiftungsblog f\u00fcr die Stiftungspraxis\",\"description\":\"#stiftungenst\u00e4rken - NPO-Expertise von NPO-Experten\",\"publisher\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#organization\",\"name\":\"stiftungsmarktplatz.eu GbR\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Logo-blog-retina.png\",\"contentUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Logo-blog-retina.png\",\"width\":140,\"height\":130,\"caption\":\"stiftungsmarktplatz.eu GbR\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/18563519\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQrF6RQRFGxTokVV4nbx25Q\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/person\\\/3a42780bf87a2088578f1e8077ccfa44\",\"name\":\"Tobias Karow\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/tobias-karow-2024-150x150.png\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/tobias-karow-2024-150x150.png\",\"contentUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/tobias-karow-2024-150x150.png\",\"caption\":\"Tobias Karow\"},\"description\":\"ist Gr\u00fcnder und Gesch\u00e4ftsf\u00fchrer von stiftungsmarktplatz.eu und im Stiftungswesen in Deutschland, \u00d6sterreich, der Schweiz und Liechtenstein seit 10 Jahren aktiv. Er ist Herausgeber der FondsFibel f\u00fcr Stiftungen &amp; NPOs, dem f\u00fchrenden Nachschlagewerk f\u00fcr Stiftungsfonds und stiftungsgeeignete Fonds (www.fondsfibel.de), Vortr\u00e4ge h\u00e4lt er vor allem zum Thema \u201aStiftungen und ihr Weg in die digitale Welt\u2018. F\u00fcr beide Themen betreibt er den Blog #stiftungenst\u00e4rken.\",\"sameAs\":[\"https:\\\/\\\/www.fondsfibel.de\"],\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/author\\\/tobias-karow\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"StiftungsAp\u00e9ro feiert Premiere in Basel - Der Stiftungsblog f\u00fcr die Stiftungspraxis","description":"Im Rahmen der SommerTour feierte der StiftungsAp\u00e9ro eine weitere Premiere. Erstmals machte der StiftungsAp\u00e9ro in der Schweiz Station, genau gesagt in Basel in den R\u00e4umen des Dachverbands gemeinn\u00fctziger Stiftungen der Schweiz, kurz profonds.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/","og_locale":"de_DE","og_type":"article","og_title":"StiftungsAp\u00e9ro feiert Premiere in Basel - Der Stiftungsblog f\u00fcr die Stiftungspraxis","og_description":"Im Rahmen der SommerTour feierte der StiftungsAp\u00e9ro eine weitere Premiere. Erstmals machte der StiftungsAp\u00e9ro in der Schweiz Station, genau gesagt in Basel in den R\u00e4umen des Dachverbands gemeinn\u00fctziger Stiftungen der Schweiz, kurz profonds.","og_url":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/","og_site_name":"Der Stiftungsblog f\u00fcr die Stiftungspraxis","article_published_time":"2024-09-19T04:42:00+00:00","article_modified_time":"2024-09-19T08:30:17+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/09\/Rueckschau-StiftungsApero-SommerTour-FinaIe.jpg","type":"image\/jpeg"}],"author":"Tobias Karow","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Tobias Karow","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/#article","isPartOf":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/"},"author":{"name":"Tobias Karow","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/person\/3a42780bf87a2088578f1e8077ccfa44"},"headline":"StiftungsAp\u00e9ro feiert Premiere in Basel","datePublished":"2024-09-19T04:42:00+00:00","dateModified":"2024-09-19T08:30:17+00:00","mainEntityOfPage":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/"},"wordCount":1135,"publisher":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#organization"},"image":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/#primaryimage"},"thumbnailUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/09\/Rueckschau-StiftungsApero-SommerTour-FinaIe.jpg","keywords":["Stiftungskommunikation","Stiftungsevent","StiftungsAp\u00e9ro","Stiftungsverm\u00f6gen","Transparenzregister","Stiftungsnetzwerk"],"articleSection":["Tipps f\u00fcr die Stiftungspraxis"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/","name":"StiftungsAp\u00e9ro feiert Premiere in Basel - Der Stiftungsblog f\u00fcr die Stiftungspraxis","isPartOf":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/#primaryimage"},"image":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/#primaryimage"},"thumbnailUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/09\/Rueckschau-StiftungsApero-SommerTour-FinaIe.jpg","datePublished":"2024-09-19T04:42:00+00:00","dateModified":"2024-09-19T08:30:17+00:00","description":"Im Rahmen der SommerTour feierte der StiftungsAp\u00e9ro eine weitere Premiere. Erstmals machte der StiftungsAp\u00e9ro in der Schweiz Station, genau gesagt in Basel in den R\u00e4umen des Dachverbands gemeinn\u00fctziger Stiftungen der Schweiz, kurz profonds.","breadcrumb":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/#primaryimage","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/09\/Rueckschau-StiftungsApero-SommerTour-FinaIe.jpg","contentUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/09\/Rueckschau-StiftungsApero-SommerTour-FinaIe.jpg","width":1200,"height":675,"caption":"R\u00fcckschau StiftungsAp\u00e9ro SommerTour FinaIe"},{"@type":"BreadcrumbList","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungsapero-feiert-premiere-in-basel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/stiftungsmarktplatz.eu\/blog\/"},{"@type":"ListItem","position":2,"name":"StiftungsAp\u00e9ro feiert Premiere in Basel"}]},{"@type":"WebSite","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#website","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/","name":"Der Stiftungsblog f\u00fcr die Stiftungspraxis","description":"#stiftungenst\u00e4rken - NPO-Expertise von NPO-Experten","publisher":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stiftungsmarktplatz.eu\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#organization","name":"stiftungsmarktplatz.eu GbR","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/03\/Logo-blog-retina.png","contentUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/03\/Logo-blog-retina.png","width":140,"height":130,"caption":"stiftungsmarktplatz.eu GbR"},"image":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/18563519\/","https:\/\/www.youtube.com\/channel\/UCQrF6RQRFGxTokVV4nbx25Q"]},{"@type":"Person","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/person\/3a42780bf87a2088578f1e8077ccfa44","name":"Tobias Karow","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/05\/tobias-karow-2024-150x150.png","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/05\/tobias-karow-2024-150x150.png","contentUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/05\/tobias-karow-2024-150x150.png","caption":"Tobias Karow"},"description":"ist Gr\u00fcnder und Gesch\u00e4ftsf\u00fchrer von stiftungsmarktplatz.eu und im Stiftungswesen in Deutschland, \u00d6sterreich, der Schweiz und Liechtenstein seit 10 Jahren aktiv. Er ist Herausgeber der FondsFibel f\u00fcr Stiftungen &amp; NPOs, dem f\u00fchrenden Nachschlagewerk f\u00fcr Stiftungsfonds und stiftungsgeeignete Fonds (www.fondsfibel.de), Vortr\u00e4ge h\u00e4lt er vor allem zum Thema \u201aStiftungen und ihr Weg in die digitale Welt\u2018. F\u00fcr beide Themen betreibt er den Blog #stiftungenst\u00e4rken.","sameAs":["https:\/\/www.fondsfibel.de"],"url":"https:\/\/stiftungsmarktplatz.eu\/blog\/author\/tobias-karow\/"}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts\/7880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/comments?post=7880"}],"version-history":[{"count":12,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts\/7880\/revisions"}],"predecessor-version":[{"id":7894,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts\/7880\/revisions\/7894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/media\/7895"}],"wp:attachment":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/media?parent=7880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/categories?post=7880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/tags?post=7880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}