{"id":3360,"date":"2022-02-21T12:16:00","date_gmt":"2022-02-21T11:16:00","guid":{"rendered":"https:\/\/stiftungsmarktplatz.eu\/blog\/?p=3360"},"modified":"2022-02-28T12:17:10","modified_gmt":"2022-02-28T11:17:10","slug":"stiftungswebsite-heisst-noch-nicht-ready","status":"publish","type":"post","link":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/","title":{"rendered":"Stiftungswebsite hei\u00dft noch nicht ready"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesezeit: <\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">Minuten<\/span><\/span>\n<p><em>Es hei\u00dft immer so sch\u00f6n, Digitalisierung, da muss man nur mitmachen, und warum so viele Stiftungen das noch nicht machen, keine Ahnung. Diesem sehr einfachen Bild, das ja auch studieren bef\u00f6rdern, nach denen gerade der deutsche Stiftungssektor im Digitalen hinterherhinkt, folgen wir nicht. Denn so einfach ist es nicht, Stiftungen auch im Digitalen \u00fcber einen Kamm zu scheren. So wie wir es immer wieder betonen, und wie es f\u00fcr uns auch richtig ist dies zu tun, gibt es 24.000 Stiftungen hierzulande, und entsprechend viele Wege, sich instutional ready f\u00fcr die digitale Welt zu machen. Wir f\u00fchlen mal den Puls.<\/em><\/p>\n\n\n\n<p>Institutional Ready, diese gro\u00dfen zwei Worte, dummerweise wieder ein Anglizismus, sind so etwas wie der rote Faden, auf den es ankommt, wenn eine Stiftung Teil der digitalen Welt werden will. Aber, und da ist das Entscheidende, es gibt hier eine Makrosicht und eine Mikrosicht. Die Makrosicht verlangt von allen Stiftungen und ihren Verantwortlichen, sich im Hier und Jetzt mit Schwung und Verve und wer wei\u00df noch was in die digitale Welt zu begeben, sich hier nicht zu verschlie\u00dfen. Ob aus einem Guss oder St\u00fcck f\u00fcr St\u00fcck, das interessiert kaum, weshalb vermutlich auch das Sender-Empf\u00e4nger-Problem einmal entstanden ist. Institutional Ready bedeutet in dieser Lesart, dass die Prozesse der Organisation so ver\u00e4ndert werden, dass sie passgenau zu den Anforderungen der digitalen Welt werden. In dieser Makrosicht interessiert das Jetzt oder Nie, weniger das Wof\u00fcr.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wof\u00fcr eigentlich soll unsere Stiftung in die digitale Welt<\/h2>\n\n\n\n<p>Stiftungen aber, aus ihrer Mikroperspektive heraus, fragen sich genau an vielen Stellen, wof\u00fcr sie eine neue Website brauchen, wof\u00fcr sie eine Spendersoftware brauchen, wof\u00fcr sie Workloads in die Cloud verlagern sollen, wof\u00fcr sie mit Stiftungskommunikation anfangen sollen. Dieses Wof\u00fcr ist dabei eine ganz pers\u00f6nliche Frage, eine ganz sensible Frage, die jede Stiftung f\u00fcr sich \u2013 in der Mikroperspektive \u2013 beantworten muss. Diese Antwort jedoch passt wom\u00f6glich nicht unbedingt auf das Jetzt oder Nie, weshalb bei Stiftungen durchaus die zur\u00fcckhaltende Hand in punkto Digitale Welt zu erkennen ist. Es ist verst\u00e4ndlich, dass Stiftungslenkerinnen und -lenker ihren Weg in die digitale Welt finden wollen, dass sie vor das Jetzt oder Nie das Wof\u00fcr setzen. Finden wir jedenfalls.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Chief Digital Officer statt Digital-Fuzzi<\/h2>\n\n\n\n<p>Denn ich kann ja nur \u201ainstitutional ready\u2018 sein, wenn ich das Ziel kenne, wenn ich wei\u00df, wohin ich mit den digitalen Werkzeugen will. Die Wege er\u00f6ffnen sich dann im Kleinen wie im Gro\u00dfen, es f\u00fchren viele Wege ins digitale Rom. Institutional ready kann f\u00fcr Stiftungen demzufolge hei\u00dfen, einmal aufzuschreiben, wo sie eigentlich stehen. Haben sie eine Stiftungswebsite, bilden sie ihre Stiftungskommunikation bereits \u00fcber digitale Tools ab, haben sie sich Gedanken zur Marke gemacht, wissen sie um die verschiedenen M\u00f6glichkeiten, Spenden oder Verm\u00f6gen im eigenen System zu controllen? Haben Sie einen Verantwortlichen benannt, der sich als CDO, also Chief Digital Officer, um die digitalen Belange k\u00fcmmert \u2013 und eben nicht nur der Digital-Fuzzi ist? Ist solch eine Person \u00fcberhaupt zu finden, ggf. aus dem eigenen Netzwerk zu rekrutieren? Wir digitale Welt von oben gelebt, vom Stiftungsvorstand her?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Stiftungen in der Thomas-Edison-Phase<\/h2>\n\n\n\n<p>Diese Bestandsaufnahme halten wir f\u00fcr extrem wichtig, denn zu wissen wo man als Stiftung im Digitalen steht, macht zweierlei klar: Einmal die Wege, die die Stiftung nicht mehr gehen braucht, und zum Anderen zeigt sie die Wege auf, die unbedingt zu gehen sind. Stiftungen werden so ein bisschen zu ihrem eigenen Thomas Edison, sie erfinden sich neu. Aber bevor sie hier an einem Ziel angekommen sind, skizzieren sie Wege, M\u00f6glichkeiten und Gegebenheiten, um bestm\u00f6glich ans Ziel zu gelangen oder um den einen oder anderen Irrweg unter Umst\u00e4nden auszuschlie\u00dfen. Aber erfahren Erfinde wissen, dass dies kaum zu vermeiden ist, dass man mit dem einen oder anderen Weg scheitert.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Bestandsaufnahme in vielen Stiftungen l\u00e4uft<\/h2>\n\n\n\n<p>Viele Stiftungen sind unserer Beobachtung nach gerade mit dieser Bestandsaufnahme befasst, diskutieren intern, welches St\u00fcck sie sich vom digitalen Kuchen abschneiden wollen und wie ihr digitaler Fu\u00dfabdruck k\u00fcnftig aussehen soll. Wir reden hier nicht nur von der Stiftungswebsite, bei der es ja nicht damit getan sie ins Netz zu stellen, sondern die gepflegt und entwickelt werden muss, damit sie nicht aus der Zeit f\u00e4llt. Digitaler Fu\u00dfabdruck ist f\u00fcr uns dasjenige digitale \u00d6kosystem, das sich eine Stiftung baut, damit sie ihre Prozesse verschlankt, damit sie kommuniziert, damit sie Projekte skalieren und ihre Mittel gezielt einsetzen kann \u2013 um nur einige Bausteinen zu nennen. Hier machen sich immer mehr Stiftungen auf den Weg, das ist klar zu sehen, aber mancher Schritt muss eben auch mit Bedacht gegangen werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Digital Ready kommt auch bei Stiftungen voran<\/h2>\n\n\n\n<p>Wir haben f\u00fcr eine Ausgabe des <a href=\"https:\/\/stiftungsmarktplatz.eu\/blog\/gute-digitalisierung-lernt-fliegen\/\">Stifterfunks Friedemann Schnur<\/a> von der Braunschweigischen Stiftung interviewt, er hat uns mit auf die Reise genommen, die \u201eseine\u201c Stiftung unternommen hat, um im Digitalen Fu\u00df zu fassen, um das eigene digitale \u00d6kosystem zu entwickeln. <a href=\"https:\/\/stiftungsmarktplatz.eu\/blog\/unsere-stiftungswebsite-war-ein-corona-projekt\/\">Dr. Agata Klaus von der Deutschen Nationalstiftung <\/a>wiederum erz\u00e4hlte uns im #FreitagsPodcast davon, wie sie beispielsweise durch die Corona-Pandemie hindurch ihre Stiftungswebsite zum Projekt gemacht haben. Oder nehmen Sie den Digital Social Summit, der mehr als 1.000 Zuschauer begeistert mit den Themen, die f\u00fcr viele Stiftungen zwar jetzt schon spannend, aber sicher erst in ein paar Jahren auf die Agenda des t\u00e4glichen Doings r\u00fccken. Es gibt sie, die Bewegung hinein ins Digitale, nur wird das von au\u00dfen noch zu wenig oft gesehen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Zusammengefasst<\/h2>\n\n\n\n<p>Stiftungen machen sich auf in die digitale Welt, machen sich digital ready. Daran besteht kein Zweifel, aber eben auch nicht daran, dass viele Stiftungen eben noch nicht so recht digitale ready sind. Mit einer neuen Stiftungswebsite ist es hier noch lange nicht getan, es braucht mehr, es braucht eine Idee, wie das digitale \u00d6kosystem der Stiftung aussehen soll. Dieses wird sich von Stiftung zu Stiftung unterscheiden, aber es wird \u2013 und davon sind wir fest \u00fcberzeugt \u2013 Stiftungshandeln besser machen. Institutional ready sind zwei Worte, die immer mehr Stiftungen mit Leben und mit Inhalt f\u00fcllen werden. Oder gibt es eine Alternative? Eben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesezeit: <\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">Minuten<\/span><\/span>Es hei\u00dft immer so sch\u00f6n, Digitalisierung, da muss man nur mitmachen, und warum so viele Stiftungen das noch nicht machen, keine Ahnung. Diesem sehr einfachen Bild, das ja auch studieren bef\u00f6rdern, nach denen gerade der deutsche Stiftungssektor im Digitalen hinterherhinkt, folgen wir nicht. Denn so einfach ist es nicht, Stiftungen auch im Digitalen \u00fcber einen Kamm zu scheren. So wie wir es immer wieder betonen, und wie es f\u00fcr uns auch richtig ist dies zu tun, gibt es 24.000 Stiftungen hierzulande, und entsprechend viele Wege, sich instutional ready f\u00fcr die digitale Welt zu machen. Wir f\u00fchlen mal den Puls.<\/p>\n","protected":false},"author":8,"featured_media":3361,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[83,145,32,35,59],"class_list":{"0":"post-3360","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-stiftungskommunikation-und-ki","8":"tag-stiftungspraxis","9":"tag-stiftungskommunikation","10":"tag-digitale-kommunikation","11":"tag-stiftungswebsite","12":"tag-digitalisierung"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stiftungswebsite hei\u00dft noch nicht ready - Der Stiftungsblog f\u00fcr die Stiftungspraxis<\/title>\n<meta name=\"description\" content=\"Es hei\u00dft immer so sch\u00f6n, Digitalisierung, da muss man nur mitmachen, und warum so viele Stiftungen das noch nicht machen, keine Ahnung. Diesem sehr einfachen Bild, das ja auch studieren bef\u00f6rdern, nach denen gerade der deutsche Stiftungssektor im Digitalen hinterherhinkt, folgen wir nicht. Denn so einfach ist es nicht, Stiftungen auch im Digitalen \u00fcber einen Kamm zu scheren. So wie wir es immer wieder betonen, und wie es f\u00fcr uns auch richtig ist dies zu tun, gibt es 24.000 Stiftungen hierzulande, und entsprechend viele Wege, sich instutional ready f\u00fcr die digitale Welt zu machen. Wir f\u00fchlen mal den Puls.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stiftungswebsite hei\u00dft noch nicht ready - Der Stiftungsblog f\u00fcr die Stiftungspraxis\" \/>\n<meta property=\"og:description\" content=\"Es hei\u00dft immer so sch\u00f6n, Digitalisierung, da muss man nur mitmachen, und warum so viele Stiftungen das noch nicht machen, keine Ahnung. Diesem sehr einfachen Bild, das ja auch studieren bef\u00f6rdern, nach denen gerade der deutsche Stiftungssektor im Digitalen hinterherhinkt, folgen wir nicht. Denn so einfach ist es nicht, Stiftungen auch im Digitalen \u00fcber einen Kamm zu scheren. So wie wir es immer wieder betonen, und wie es f\u00fcr uns auch richtig ist dies zu tun, gibt es 24.000 Stiftungen hierzulande, und entsprechend viele Wege, sich instutional ready f\u00fcr die digitale Welt zu machen. Wir f\u00fchlen mal den Puls.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/\" \/>\n<meta property=\"og:site_name\" content=\"Der Stiftungsblog f\u00fcr die Stiftungspraxis\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-21T11:16:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-28T11:17:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2022\/02\/Institutional-Ready.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tobias Karow\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tobias Karow\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungswebsite-heisst-noch-nicht-ready\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungswebsite-heisst-noch-nicht-ready\\\/\"},\"author\":{\"name\":\"Tobias Karow\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/person\\\/3a42780bf87a2088578f1e8077ccfa44\"},\"headline\":\"Stiftungswebsite hei\u00dft noch nicht ready\",\"datePublished\":\"2022-02-21T11:16:00+00:00\",\"dateModified\":\"2022-02-28T11:17:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungswebsite-heisst-noch-nicht-ready\\\/\"},\"wordCount\":1022,\"publisher\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungswebsite-heisst-noch-nicht-ready\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Institutional-Ready.jpg\",\"keywords\":[\"Stiftungspraxis\",\"Stiftungskommunikation\",\"digitale Kommunikation\",\"Stiftungswebsite\",\"Digitalisierung\"],\"articleSection\":[\"Stiftungskommunikation und KI\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungswebsite-heisst-noch-nicht-ready\\\/\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungswebsite-heisst-noch-nicht-ready\\\/\",\"name\":\"Stiftungswebsite hei\u00dft noch nicht ready - Der Stiftungsblog f\u00fcr die Stiftungspraxis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungswebsite-heisst-noch-nicht-ready\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungswebsite-heisst-noch-nicht-ready\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Institutional-Ready.jpg\",\"datePublished\":\"2022-02-21T11:16:00+00:00\",\"dateModified\":\"2022-02-28T11:17:10+00:00\",\"description\":\"Es hei\u00dft immer so sch\u00f6n, Digitalisierung, da muss man nur mitmachen, und warum so viele Stiftungen das noch nicht machen, keine Ahnung. Diesem sehr einfachen Bild, das ja auch studieren bef\u00f6rdern, nach denen gerade der deutsche Stiftungssektor im Digitalen hinterherhinkt, folgen wir nicht. Denn so einfach ist es nicht, Stiftungen auch im Digitalen \u00fcber einen Kamm zu scheren. So wie wir es immer wieder betonen, und wie es f\u00fcr uns auch richtig ist dies zu tun, gibt es 24.000 Stiftungen hierzulande, und entsprechend viele Wege, sich instutional ready f\u00fcr die digitale Welt zu machen. Wir f\u00fchlen mal den Puls.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungswebsite-heisst-noch-nicht-ready\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungswebsite-heisst-noch-nicht-ready\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungswebsite-heisst-noch-nicht-ready\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Institutional-Ready.jpg\",\"contentUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Institutional-Ready.jpg\",\"width\":1200,\"height\":675,\"caption\":\"Institutional-Ready\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungswebsite-heisst-noch-nicht-ready\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stiftungswebsite hei\u00dft noch nicht ready\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/\",\"name\":\"Der Stiftungsblog f\u00fcr die Stiftungspraxis\",\"description\":\"#stiftungenst\u00e4rken - NPO-Expertise von NPO-Experten\",\"publisher\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#organization\",\"name\":\"stiftungsmarktplatz.eu GbR\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Logo-blog-retina.png\",\"contentUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Logo-blog-retina.png\",\"width\":140,\"height\":130,\"caption\":\"stiftungsmarktplatz.eu GbR\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/18563519\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQrF6RQRFGxTokVV4nbx25Q\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/person\\\/3a42780bf87a2088578f1e8077ccfa44\",\"name\":\"Tobias Karow\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/tobias-karow-2024-150x150.png\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/tobias-karow-2024-150x150.png\",\"contentUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/tobias-karow-2024-150x150.png\",\"caption\":\"Tobias Karow\"},\"description\":\"ist Gr\u00fcnder und Gesch\u00e4ftsf\u00fchrer von stiftungsmarktplatz.eu und im Stiftungswesen in Deutschland, \u00d6sterreich, der Schweiz und Liechtenstein seit 10 Jahren aktiv. Er ist Herausgeber der FondsFibel f\u00fcr Stiftungen &amp; NPOs, dem f\u00fchrenden Nachschlagewerk f\u00fcr Stiftungsfonds und stiftungsgeeignete Fonds (www.fondsfibel.de), Vortr\u00e4ge h\u00e4lt er vor allem zum Thema \u201aStiftungen und ihr Weg in die digitale Welt\u2018. F\u00fcr beide Themen betreibt er den Blog #stiftungenst\u00e4rken.\",\"sameAs\":[\"https:\\\/\\\/www.fondsfibel.de\"],\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/author\\\/tobias-karow\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stiftungswebsite hei\u00dft noch nicht ready - Der Stiftungsblog f\u00fcr die Stiftungspraxis","description":"Es hei\u00dft immer so sch\u00f6n, Digitalisierung, da muss man nur mitmachen, und warum so viele Stiftungen das noch nicht machen, keine Ahnung. Diesem sehr einfachen Bild, das ja auch studieren bef\u00f6rdern, nach denen gerade der deutsche Stiftungssektor im Digitalen hinterherhinkt, folgen wir nicht. Denn so einfach ist es nicht, Stiftungen auch im Digitalen \u00fcber einen Kamm zu scheren. So wie wir es immer wieder betonen, und wie es f\u00fcr uns auch richtig ist dies zu tun, gibt es 24.000 Stiftungen hierzulande, und entsprechend viele Wege, sich instutional ready f\u00fcr die digitale Welt zu machen. Wir f\u00fchlen mal den Puls.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/","og_locale":"de_DE","og_type":"article","og_title":"Stiftungswebsite hei\u00dft noch nicht ready - Der Stiftungsblog f\u00fcr die Stiftungspraxis","og_description":"Es hei\u00dft immer so sch\u00f6n, Digitalisierung, da muss man nur mitmachen, und warum so viele Stiftungen das noch nicht machen, keine Ahnung. Diesem sehr einfachen Bild, das ja auch studieren bef\u00f6rdern, nach denen gerade der deutsche Stiftungssektor im Digitalen hinterherhinkt, folgen wir nicht. Denn so einfach ist es nicht, Stiftungen auch im Digitalen \u00fcber einen Kamm zu scheren. So wie wir es immer wieder betonen, und wie es f\u00fcr uns auch richtig ist dies zu tun, gibt es 24.000 Stiftungen hierzulande, und entsprechend viele Wege, sich instutional ready f\u00fcr die digitale Welt zu machen. Wir f\u00fchlen mal den Puls.","og_url":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/","og_site_name":"Der Stiftungsblog f\u00fcr die Stiftungspraxis","article_published_time":"2022-02-21T11:16:00+00:00","article_modified_time":"2022-02-28T11:17:10+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2022\/02\/Institutional-Ready.jpg","type":"image\/jpeg"}],"author":"Tobias Karow","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Tobias Karow","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/#article","isPartOf":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/"},"author":{"name":"Tobias Karow","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/person\/3a42780bf87a2088578f1e8077ccfa44"},"headline":"Stiftungswebsite hei\u00dft noch nicht ready","datePublished":"2022-02-21T11:16:00+00:00","dateModified":"2022-02-28T11:17:10+00:00","mainEntityOfPage":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/"},"wordCount":1022,"publisher":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#organization"},"image":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/#primaryimage"},"thumbnailUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2022\/02\/Institutional-Ready.jpg","keywords":["Stiftungspraxis","Stiftungskommunikation","digitale Kommunikation","Stiftungswebsite","Digitalisierung"],"articleSection":["Stiftungskommunikation und KI"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/","name":"Stiftungswebsite hei\u00dft noch nicht ready - Der Stiftungsblog f\u00fcr die Stiftungspraxis","isPartOf":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/#primaryimage"},"image":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/#primaryimage"},"thumbnailUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2022\/02\/Institutional-Ready.jpg","datePublished":"2022-02-21T11:16:00+00:00","dateModified":"2022-02-28T11:17:10+00:00","description":"Es hei\u00dft immer so sch\u00f6n, Digitalisierung, da muss man nur mitmachen, und warum so viele Stiftungen das noch nicht machen, keine Ahnung. Diesem sehr einfachen Bild, das ja auch studieren bef\u00f6rdern, nach denen gerade der deutsche Stiftungssektor im Digitalen hinterherhinkt, folgen wir nicht. Denn so einfach ist es nicht, Stiftungen auch im Digitalen \u00fcber einen Kamm zu scheren. So wie wir es immer wieder betonen, und wie es f\u00fcr uns auch richtig ist dies zu tun, gibt es 24.000 Stiftungen hierzulande, und entsprechend viele Wege, sich instutional ready f\u00fcr die digitale Welt zu machen. Wir f\u00fchlen mal den Puls.","breadcrumb":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/#primaryimage","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2022\/02\/Institutional-Ready.jpg","contentUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2022\/02\/Institutional-Ready.jpg","width":1200,"height":675,"caption":"Institutional-Ready"},{"@type":"BreadcrumbList","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungswebsite-heisst-noch-nicht-ready\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/stiftungsmarktplatz.eu\/blog\/"},{"@type":"ListItem","position":2,"name":"Stiftungswebsite hei\u00dft noch nicht ready"}]},{"@type":"WebSite","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#website","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/","name":"Der Stiftungsblog f\u00fcr die Stiftungspraxis","description":"#stiftungenst\u00e4rken - NPO-Expertise von NPO-Experten","publisher":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stiftungsmarktplatz.eu\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#organization","name":"stiftungsmarktplatz.eu GbR","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/03\/Logo-blog-retina.png","contentUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/03\/Logo-blog-retina.png","width":140,"height":130,"caption":"stiftungsmarktplatz.eu GbR"},"image":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/18563519\/","https:\/\/www.youtube.com\/channel\/UCQrF6RQRFGxTokVV4nbx25Q"]},{"@type":"Person","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/person\/3a42780bf87a2088578f1e8077ccfa44","name":"Tobias Karow","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/05\/tobias-karow-2024-150x150.png","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/05\/tobias-karow-2024-150x150.png","contentUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/05\/tobias-karow-2024-150x150.png","caption":"Tobias Karow"},"description":"ist Gr\u00fcnder und Gesch\u00e4ftsf\u00fchrer von stiftungsmarktplatz.eu und im Stiftungswesen in Deutschland, \u00d6sterreich, der Schweiz und Liechtenstein seit 10 Jahren aktiv. Er ist Herausgeber der FondsFibel f\u00fcr Stiftungen &amp; NPOs, dem f\u00fchrenden Nachschlagewerk f\u00fcr Stiftungsfonds und stiftungsgeeignete Fonds (www.fondsfibel.de), Vortr\u00e4ge h\u00e4lt er vor allem zum Thema \u201aStiftungen und ihr Weg in die digitale Welt\u2018. F\u00fcr beide Themen betreibt er den Blog #stiftungenst\u00e4rken.","sameAs":["https:\/\/www.fondsfibel.de"],"url":"https:\/\/stiftungsmarktplatz.eu\/blog\/author\/tobias-karow\/"}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts\/3360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/comments?post=3360"}],"version-history":[{"count":2,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts\/3360\/revisions"}],"predecessor-version":[{"id":3364,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts\/3360\/revisions\/3364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/media\/3361"}],"wp:attachment":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/media?parent=3360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/categories?post=3360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/tags?post=3360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}