{"id":1878,"date":"2021-03-04T16:26:11","date_gmt":"2021-03-04T15:26:11","guid":{"rendered":"https:\/\/stiftungsmarktplatz.eu\/blog\/?p=1878"},"modified":"2021-04-29T16:26:38","modified_gmt":"2021-04-29T14:26:38","slug":"stiftungskommunikation-a-la-billy-crystal","status":"publish","type":"post","link":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/","title":{"rendered":"Stiftungskommunikation \u00e0 la Billy Crystal"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesezeit: <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">Minuten<\/span><\/span>\n<p><em>Charles Bronson galt als ein Schauspieler, der seine Geschichte \u00fcber Mimik und Pr\u00e4senz transportierte, Eddy Murphy dagegen war und ist wohl die Quasselstrippe schlechthin. Spricht er nicht 684 Worte in der Minute verpasst er was, so in etwa lassen sich seine Rolle interpretieren. F\u00fcr Stiftungen ist in der Stiftungskommunikation vermutlich weder der Bronson-Weg noch der Murphy-Weg der passende, es d\u00fcrfte ich die Richtung Billy Crystal gehen.<\/em><\/p>\n\n\n\n<p>Billy Crystal konnte als Schauspieler so richtig drauflos quasseln, er konnte Monologe halten \u00fcber das Leben, er konnte sein Gegen\u00fcber m\u00fcrbe quatschen. Genauso konnte er aber auch mit wenigen Worten wirken, konnte seiner Rolle dadurch die notwendige Tiefe verleihen. Dieses Spielen mit den Stilmitteln ist etwas, das auch Stiftungen in der Stiftungskommunikation beherzigen sollten, denn eine Geschichte immer gleich zu temperieren, das kann sich auch als Rohrkrepierer erweisen. Was meinen wir damit. Es geh\u00f6rt zur modernen Kommunikation dazu, sich Gedanken \u00fcber die Frequenz, die Inhalte und die Art und Weise des Erz\u00e4hlens der Geschichte zu machen. Geschichten immer auf die gleiche Weise zu erz\u00e4hlen, das wird auch irgendwann dr\u00f6ge.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">STIFTUNGSKOMMUNIKATION ZWISCHEN CRYSTAL UND MURPHY<\/h2>\n\n\n\n<p>Stiftungen m\u00fcssen, wenn sie Stiftungskommunikation betreiben, \u00fcberlegen, wann sie ihrem Billy Crystal ein bisschen mehr von Charles Bronson mitgeben, und wann etwas mehr von Eddy Murphy. Stiftungen sollten ihre Stiftungskommunikation temperieren. Es gibt manche Stiftungen, die dr\u00fccken immer gleich auf die Tr\u00e4nendr\u00fcse, es gibt wieder andere, die erz\u00e4hlen nur von Erfolgen und was alles funktioniert hat. Die Wahrheit ist hier: Es hat nat\u00fcrlich nicht alles funktioniert, es gab Fehlschl\u00e4ge, und bei keinem Projekt rolle ich eine Blaupause aus und schon rollt der Laden in genau die Richtung, die ich mir vorgestellt habe. Das glaubt mir keiner, entsprechend ist auch eine stets so temperierte Stiftungskommunikation keine, die verf\u00e4ngt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">WIE FREQUENT SOLL STIFTUNGSKOMMUNIKATION SEIN<\/h2>\n\n\n\n<p>Stattdessen kann es sinnvoll sein, durchaus von diesen Problemchen zu erz\u00e4hlen und solche Geschichten mit den H\u00fcrden zu mixen mit den Geschichten des Gelingens. Stiftungskommunikation wird dann umso authentischer. Damit es dann so ein Charles Bronson in der Stiftungskommunikation wird, gilt es, die Frequenz dessen zu hinterfragen. Wir gehen also an dieser Stelle davon aus, dass Stiftungen um den Wert ihrer Geschichten wissen, dass sie diese erz\u00e4hlen wollen und dazu dann auch wieder in der Lage sind. Das Setup stimmt also. Jetzt m\u00fcssen sich Stiftungen mit der Frequenz ihrer kommunikativen Bem\u00fchungen besch\u00e4ftigen, und an diesem kleinen Detail h\u00e4ngt manchmal jede Menge.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">WENIGER IST MANCHMAL DOCH MEHR<\/h2>\n\n\n\n<p>Denn ob sie wie Charles Bronson oder Eddy Murphy temperieren, das entscheidet oft dar\u00fcber, ob eine kommunikative Anstrengung verf\u00e4ngt oder nicht. Stiftungskommunikation kann durchaus davon profitieren, etwas weniger zu trommeln, denn das verleiht den kommunizierten Geschichten eine gewisse Tiefe und auch eine gewisse Bedeutung. Auch nehmen Nutzer von Informationen bestimmte Inhalte vielleicht eher wahr, wenn nicht jeden Tag etwas von dieser oder jenen Stiftung h\u00f6ren, sondern wenn sie etwas h\u00f6ren oder sehen oder lesen, sobald eine wirklich nutzwertige Information kommuniziert wird. Es kann sich f\u00fcr Stiftungen also auszahlen, Charles Bronson-m\u00e4\u00dfig zu kommunizieren, weil dies die Wahrnehmung gezielt lenkt. Einerseits.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ETWAS MEHR FREQUENZ VON ZEIT ZU ZEIT<\/h2>\n\n\n\n<p>Andererseits kann es aus Stiftungssicht sinnvoll sein, zu manchen Zeitpunkten n\u2018 bisschen auf Eddy Murphy zu machen und die Frequenz der Stiftungskommunikation hoch zu halten. Wird zum Beispiel eine Veranstaltung durchgef\u00fchrt, dann muss die Frequenz im Vorfeld nach oben gehen, um zur Veranstaltung eine Awareness aufzubauen und zumindest den Termin im Kopf zu verankern. Gleiches gilt auch f\u00fcr ein neues Projekt, das anl\u00e4uft, hier kann ebenfalls eine h\u00f6here Frequenz sinnvoll sein. Oder wenn Jahresbericht bzw. T\u00e4tigkeitsbericht ver\u00f6ffentlicht wurden. Dies ist ein Event an sich, und hier nur einmalig eine kurze Notiz zu kommunizieren, w\u00fcrde schlichtweg verpuffen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">KOMMUNIZIREN GEHT VOR INFORMIEREN<\/h2>\n\n\n\n<p>Aber die Frequenz der Stiftungskommunikation ist noch aus einem anderen Grund heraus wichtig. Kommunikation ist weitaus mehr als das Vermitteln einer Information, entsprechend ist das Spiel mit der Frequenz eines, das ich mit dem Nutzer spiele. Nat\u00fcrlich informiert eine Stiftung seri\u00f6s und auf den Punkt, aber sie tut dies in unterschiedlicher Frequenz und macht sich damit interessant. Interessanter jedenfalls als andere, die immer in der gleichen Frequenz etwas erz\u00e4hlen, dar\u00fcber aber das Kommunizieren vergessen. Kommuniziere ich aber, biete ich dem Nutzer also dieses Spiel mit der Frequenz an, steigere ich dar\u00fcber die Chance, dass meine Information auch verf\u00e4ngt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ZUSAMMENGEFASST<\/h2>\n\n\n\n<p>Stiftungskommunikation ist heute mehr denn je wichtiger Bestandteil der t\u00e4glichen Stiftungspraxis geworden. Dort wo das in den Stiftungsgremien noch nicht angekommen ist, wird sich in den kommenden Jahren Einiges \u00e4ndern m\u00fcssen, Stiftungsverantwortliche werden sich hier den Zeichen der Zeit nicht entziehen k\u00f6nnen. Wenn ich als Stiftung kommuniziere, dann sollte ich auch das Spiel mit der Frequenz im Auge behalten \u2013 und f\u00fcr die Stiftungskommunikation nutzen. Nur auf Eddy Murphy bzw. nur auf Charles Bronson zu machen, das kann in den heutigen Zeiten zu wenig sein. Es braucht beides, so wie ein guter Film immer auch beide Charaktere besetzt. Oder eben Stiftungskommunikation \u00e0 la Billy Crystal.<br><\/p>\n\n\n\n<p><em><br><br><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesezeit: <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">Minuten<\/span><\/span>Charles Bronson galt als ein Schauspieler, der seine Geschichte \u00fcber Mimik und Pr\u00e4senz transportierte, Eddy Murphy dagegen war und ist wohl die Quasselstrippe schlechthin. Spricht er nicht 684 Worte in der Minute verpasst er was, so in etwa lassen sich seine Rolle interpretieren. F\u00fcr Stiftungen ist in der Stiftungskommunikation vermutlich weder der Bronson-Weg noch der Murphy-Weg der passende, es d\u00fcrfte ich die Richtung Billy Crystal gehen.<\/p>\n","protected":false},"author":8,"featured_media":1879,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[19,35,83,145],"class_list":{"0":"post-1878","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-stiftungskommunikation-und-ki","8":"tag-stiftungen","9":"tag-stiftungswebsite","10":"tag-stiftungspraxis","11":"tag-stiftungskommunikation"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stiftungskommunikation \u00e0 la Billy Crystal - Der Stiftungsblog f\u00fcr die Stiftungspraxis<\/title>\n<meta name=\"description\" content=\"Charles Bronson galt als ein Schauspieler, der seine Geschichte \u00fcber Mimik und Pr\u00e4senz transportierte, Eddy Murphy dagegen war und ist wohl die Quasselstrippe schlechthin. Spricht er nicht 684 Worte in der Minute verpasst er was, so in etwa lassen sich seine Rolle interpretieren. F\u00fcr Stiftungen ist in der Stiftungskommunikation vermutlich weder der Bronson-Weg noch der Murphy-Weg der passende, es d\u00fcrfte ich die Richtung Billy Crystal gehen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stiftungskommunikation \u00e0 la Billy Crystal - Der Stiftungsblog f\u00fcr die Stiftungspraxis\" \/>\n<meta property=\"og:description\" content=\"Charles Bronson galt als ein Schauspieler, der seine Geschichte \u00fcber Mimik und Pr\u00e4senz transportierte, Eddy Murphy dagegen war und ist wohl die Quasselstrippe schlechthin. Spricht er nicht 684 Worte in der Minute verpasst er was, so in etwa lassen sich seine Rolle interpretieren. F\u00fcr Stiftungen ist in der Stiftungskommunikation vermutlich weder der Bronson-Weg noch der Murphy-Weg der passende, es d\u00fcrfte ich die Richtung Billy Crystal gehen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/\" \/>\n<meta property=\"og:site_name\" content=\"Der Stiftungsblog f\u00fcr die Stiftungspraxis\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-04T15:26:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-29T14:26:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2021\/03\/Stiftungskommunikation-Billy-Crystal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tobias Karow\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tobias Karow\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungskommunikation-a-la-billy-crystal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungskommunikation-a-la-billy-crystal\\\/\"},\"author\":{\"name\":\"Tobias Karow\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/person\\\/3a42780bf87a2088578f1e8077ccfa44\"},\"headline\":\"Stiftungskommunikation \u00e0 la Billy Crystal\",\"datePublished\":\"2021-03-04T15:26:11+00:00\",\"dateModified\":\"2021-04-29T14:26:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungskommunikation-a-la-billy-crystal\\\/\"},\"wordCount\":856,\"publisher\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungskommunikation-a-la-billy-crystal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Stiftungskommunikation-Billy-Crystal.jpg\",\"keywords\":[\"Stiftungen\",\"Stiftungswebsite\",\"Stiftungspraxis\",\"Stiftungskommunikation\"],\"articleSection\":[\"Stiftungskommunikation und KI\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungskommunikation-a-la-billy-crystal\\\/\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungskommunikation-a-la-billy-crystal\\\/\",\"name\":\"Stiftungskommunikation \u00e0 la Billy Crystal - Der Stiftungsblog f\u00fcr die Stiftungspraxis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungskommunikation-a-la-billy-crystal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungskommunikation-a-la-billy-crystal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Stiftungskommunikation-Billy-Crystal.jpg\",\"datePublished\":\"2021-03-04T15:26:11+00:00\",\"dateModified\":\"2021-04-29T14:26:38+00:00\",\"description\":\"Charles Bronson galt als ein Schauspieler, der seine Geschichte \u00fcber Mimik und Pr\u00e4senz transportierte, Eddy Murphy dagegen war und ist wohl die Quasselstrippe schlechthin. Spricht er nicht 684 Worte in der Minute verpasst er was, so in etwa lassen sich seine Rolle interpretieren. F\u00fcr Stiftungen ist in der Stiftungskommunikation vermutlich weder der Bronson-Weg noch der Murphy-Weg der passende, es d\u00fcrfte ich die Richtung Billy Crystal gehen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungskommunikation-a-la-billy-crystal\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungskommunikation-a-la-billy-crystal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungskommunikation-a-la-billy-crystal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Stiftungskommunikation-Billy-Crystal.jpg\",\"contentUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Stiftungskommunikation-Billy-Crystal.jpg\",\"width\":1200,\"height\":675,\"caption\":\"Stiftungskommunikation Billy Crystal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stiftungskommunikation-a-la-billy-crystal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stiftungskommunikation \u00e0 la Billy Crystal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/\",\"name\":\"Der Stiftungsblog f\u00fcr die Stiftungspraxis\",\"description\":\"#stiftungenst\u00e4rken - NPO-Expertise von NPO-Experten\",\"publisher\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#organization\",\"name\":\"stiftungsmarktplatz.eu GbR\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Logo-blog-retina.png\",\"contentUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Logo-blog-retina.png\",\"width\":140,\"height\":130,\"caption\":\"stiftungsmarktplatz.eu GbR\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/18563519\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQrF6RQRFGxTokVV4nbx25Q\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/person\\\/3a42780bf87a2088578f1e8077ccfa44\",\"name\":\"Tobias Karow\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/tobias-karow-2024-150x150.png\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/tobias-karow-2024-150x150.png\",\"contentUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/tobias-karow-2024-150x150.png\",\"caption\":\"Tobias Karow\"},\"description\":\"ist Gr\u00fcnder und Gesch\u00e4ftsf\u00fchrer von stiftungsmarktplatz.eu und im Stiftungswesen in Deutschland, \u00d6sterreich, der Schweiz und Liechtenstein seit 10 Jahren aktiv. Er ist Herausgeber der FondsFibel f\u00fcr Stiftungen &amp; NPOs, dem f\u00fchrenden Nachschlagewerk f\u00fcr Stiftungsfonds und stiftungsgeeignete Fonds (www.fondsfibel.de), Vortr\u00e4ge h\u00e4lt er vor allem zum Thema \u201aStiftungen und ihr Weg in die digitale Welt\u2018. F\u00fcr beide Themen betreibt er den Blog #stiftungenst\u00e4rken.\",\"sameAs\":[\"https:\\\/\\\/www.fondsfibel.de\"],\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/author\\\/tobias-karow\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stiftungskommunikation \u00e0 la Billy Crystal - Der Stiftungsblog f\u00fcr die Stiftungspraxis","description":"Charles Bronson galt als ein Schauspieler, der seine Geschichte \u00fcber Mimik und Pr\u00e4senz transportierte, Eddy Murphy dagegen war und ist wohl die Quasselstrippe schlechthin. Spricht er nicht 684 Worte in der Minute verpasst er was, so in etwa lassen sich seine Rolle interpretieren. F\u00fcr Stiftungen ist in der Stiftungskommunikation vermutlich weder der Bronson-Weg noch der Murphy-Weg der passende, es d\u00fcrfte ich die Richtung Billy Crystal gehen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/","og_locale":"de_DE","og_type":"article","og_title":"Stiftungskommunikation \u00e0 la Billy Crystal - Der Stiftungsblog f\u00fcr die Stiftungspraxis","og_description":"Charles Bronson galt als ein Schauspieler, der seine Geschichte \u00fcber Mimik und Pr\u00e4senz transportierte, Eddy Murphy dagegen war und ist wohl die Quasselstrippe schlechthin. Spricht er nicht 684 Worte in der Minute verpasst er was, so in etwa lassen sich seine Rolle interpretieren. F\u00fcr Stiftungen ist in der Stiftungskommunikation vermutlich weder der Bronson-Weg noch der Murphy-Weg der passende, es d\u00fcrfte ich die Richtung Billy Crystal gehen.","og_url":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/","og_site_name":"Der Stiftungsblog f\u00fcr die Stiftungspraxis","article_published_time":"2021-03-04T15:26:11+00:00","article_modified_time":"2021-04-29T14:26:38+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2021\/03\/Stiftungskommunikation-Billy-Crystal.jpg","type":"image\/jpeg"}],"author":"Tobias Karow","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Tobias Karow","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/#article","isPartOf":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/"},"author":{"name":"Tobias Karow","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/person\/3a42780bf87a2088578f1e8077ccfa44"},"headline":"Stiftungskommunikation \u00e0 la Billy Crystal","datePublished":"2021-03-04T15:26:11+00:00","dateModified":"2021-04-29T14:26:38+00:00","mainEntityOfPage":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/"},"wordCount":856,"publisher":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#organization"},"image":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/#primaryimage"},"thumbnailUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2021\/03\/Stiftungskommunikation-Billy-Crystal.jpg","keywords":["Stiftungen","Stiftungswebsite","Stiftungspraxis","Stiftungskommunikation"],"articleSection":["Stiftungskommunikation und KI"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/","name":"Stiftungskommunikation \u00e0 la Billy Crystal - Der Stiftungsblog f\u00fcr die Stiftungspraxis","isPartOf":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/#primaryimage"},"image":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/#primaryimage"},"thumbnailUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2021\/03\/Stiftungskommunikation-Billy-Crystal.jpg","datePublished":"2021-03-04T15:26:11+00:00","dateModified":"2021-04-29T14:26:38+00:00","description":"Charles Bronson galt als ein Schauspieler, der seine Geschichte \u00fcber Mimik und Pr\u00e4senz transportierte, Eddy Murphy dagegen war und ist wohl die Quasselstrippe schlechthin. Spricht er nicht 684 Worte in der Minute verpasst er was, so in etwa lassen sich seine Rolle interpretieren. F\u00fcr Stiftungen ist in der Stiftungskommunikation vermutlich weder der Bronson-Weg noch der Murphy-Weg der passende, es d\u00fcrfte ich die Richtung Billy Crystal gehen.","breadcrumb":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/#primaryimage","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2021\/03\/Stiftungskommunikation-Billy-Crystal.jpg","contentUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2021\/03\/Stiftungskommunikation-Billy-Crystal.jpg","width":1200,"height":675,"caption":"Stiftungskommunikation Billy Crystal"},{"@type":"BreadcrumbList","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stiftungskommunikation-a-la-billy-crystal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/stiftungsmarktplatz.eu\/blog\/"},{"@type":"ListItem","position":2,"name":"Stiftungskommunikation \u00e0 la Billy Crystal"}]},{"@type":"WebSite","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#website","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/","name":"Der Stiftungsblog f\u00fcr die Stiftungspraxis","description":"#stiftungenst\u00e4rken - NPO-Expertise von NPO-Experten","publisher":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stiftungsmarktplatz.eu\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#organization","name":"stiftungsmarktplatz.eu GbR","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/03\/Logo-blog-retina.png","contentUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/03\/Logo-blog-retina.png","width":140,"height":130,"caption":"stiftungsmarktplatz.eu GbR"},"image":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/18563519\/","https:\/\/www.youtube.com\/channel\/UCQrF6RQRFGxTokVV4nbx25Q"]},{"@type":"Person","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/person\/3a42780bf87a2088578f1e8077ccfa44","name":"Tobias Karow","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/05\/tobias-karow-2024-150x150.png","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/05\/tobias-karow-2024-150x150.png","contentUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/05\/tobias-karow-2024-150x150.png","caption":"Tobias Karow"},"description":"ist Gr\u00fcnder und Gesch\u00e4ftsf\u00fchrer von stiftungsmarktplatz.eu und im Stiftungswesen in Deutschland, \u00d6sterreich, der Schweiz und Liechtenstein seit 10 Jahren aktiv. Er ist Herausgeber der FondsFibel f\u00fcr Stiftungen &amp; NPOs, dem f\u00fchrenden Nachschlagewerk f\u00fcr Stiftungsfonds und stiftungsgeeignete Fonds (www.fondsfibel.de), Vortr\u00e4ge h\u00e4lt er vor allem zum Thema \u201aStiftungen und ihr Weg in die digitale Welt\u2018. F\u00fcr beide Themen betreibt er den Blog #stiftungenst\u00e4rken.","sameAs":["https:\/\/www.fondsfibel.de"],"url":"https:\/\/stiftungsmarktplatz.eu\/blog\/author\/tobias-karow\/"}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts\/1878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/comments?post=1878"}],"version-history":[{"count":1,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts\/1878\/revisions"}],"predecessor-version":[{"id":1880,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts\/1878\/revisions\/1880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/media\/1879"}],"wp:attachment":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/media?parent=1878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/categories?post=1878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/tags?post=1878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}