{"id":1317,"date":"2020-07-10T09:45:11","date_gmt":"2020-07-10T07:45:11","guid":{"rendered":"https:\/\/stiftungsmarktplatz.eu\/blog\/?p=1317"},"modified":"2021-10-08T14:30:37","modified_gmt":"2021-10-08T12:30:37","slug":"stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen","status":"publish","type":"post","link":"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/","title":{"rendered":"Stellschrauben im Stiftungsverm\u00f6gen bitte jetzt drehen"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesezeit: <\/span> <span class=\"rt-time\"> &lt; 1<\/span> <span class=\"rt-label rt-postfix\">Minute<\/span><\/span>\n<p>Stiftungsverm\u00f6gen anzulegen, ganz gleich ob delegiert an Stiftungsfonds, in die H\u00e4nde von Verm\u00f6gensverwaltern gelegt oder selbst gemacht, bedarf heute ein paar ganz grundlegender \u00c4nderungen im Vergleich zu den vergangenen 10, 20 Jahren. <\/p>\n\n\n\n<p>Mit dem Fonds- und Stiftungsexperten Frank Wettlauffer sprachen wir dar\u00fcber, was im Stiftungsverm\u00f6gen heute z\u00e4hlt, warum Stiftungen nicht nur auf Stiftungsfonds sondern eben auch andere stiftungsgeeignete Fonds schauen sollten und was es langfristig f\u00fcr das Stiftungsverm\u00f6gen wirklich bedeutet, wenn der Niedrigzins lange niedrig bleibt.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-cover has-background-dim\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"485\" class=\"wp-block-cover__image-background wp-image-96\" alt=\"\" src=\"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/02\/bienen-podcast-2.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/02\/bienen-podcast-2.jpg 1000w, https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/02\/bienen-podcast-2-300x146.jpg 300w, https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/02\/bienen-podcast-2-768x372.jpg 768w, https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/02\/bienen-podcast-2-696x338.jpg 696w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/02\/podcast-icon-90px.png\" alt=\"\" class=\"wp-image-95\"\/><\/figure><\/div>\n\n\n\n<h2 class=\"has-text-align-center has-text-color wp-block-heading\" style=\"color:#8b2e7d\"><strong>PODCAST<\/strong><br> \u201eStellschrauben im Stiftungsverm\u00f6gen <br>bitte jetzt drehen\u201c<\/h2>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/stiftungenstaerken.podcaster.de\/download\/Podcast-Ahoi-NPO-Folge13-Frank-Wettlauffer.mp3\"><\/audio><\/figure>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesezeit: <\/span> <span class=\"rt-time\"> &lt; 1<\/span> <span class=\"rt-label rt-postfix\">Minute<\/span><\/span>Stiftungsverm\u00f6gen anzulegen, ganz gleich ob delegiert an Stiftungsfonds, in die H\u00e4nde von Verm\u00f6gensverwaltern gelegt oder selbst gemacht, bedarf heute ein paar ganz grundlegender \u00c4nderungen im Vergleich zu den vergangenen 10, 20 Jahren. Mit dem Fonds- und Stiftungsexperten Frank Wettlauffer sprachen wir dar\u00fcber, was im Stiftungsverm\u00f6gen heute z\u00e4hlt, warum Stiftungen nicht nur auf Stiftungsfonds sondern eben auch andere stiftungsgeeignete Fonds schauen sollten und was es langfristig f\u00fcr das Stiftungsverm\u00f6gen wirklich bedeutet, wenn der Niedrigzins lange niedrig bleibt.  <\/p>\n","protected":false},"author":8,"featured_media":1322,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[5,9],"tags":[26,27,54,112,14,16,23],"class_list":{"0":"post-1317","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-stiftungsvermoegen-und-stiftungsfonds","8":"category-stiftungenstaerken","9":"tag-podcast","10":"tag-stiftungsvermoegen","11":"tag-niedrigzins","12":"tag-freitags-podcast","13":"tag-stiftungsfonds","14":"tag-corona-crash","15":"tag-stiftungsgeeignete-fonds"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stellschrauben im Stiftungsverm\u00f6gen bitte jetzt drehen - Der Stiftungsblog f\u00fcr die Stiftungspraxis<\/title>\n<meta name=\"description\" content=\"Stiftungsverm\u00f6gen anzulegen, ganz gleich ob delegiert an Stiftungsfonds, in die H\u00e4nde von Verm\u00f6gensverwaltern gelegt oder selbst gemacht, bedarf heute ein paar ganz grundlegender \u00c4nderungen im Vergleich zu den vergangenen 10, 20 Jahren. Mit dem Fonds- und Stiftungsexperten Frank Wettlauffer sprachen wir dar\u00fcber, was im Stiftungsverm\u00f6gen heute z\u00e4hlt\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stellschrauben im Stiftungsverm\u00f6gen bitte jetzt drehen - Der Stiftungsblog f\u00fcr die Stiftungspraxis\" \/>\n<meta property=\"og:description\" content=\"Stiftungsverm\u00f6gen anzulegen, ganz gleich ob delegiert an Stiftungsfonds, in die H\u00e4nde von Verm\u00f6gensverwaltern gelegt oder selbst gemacht, bedarf heute ein paar ganz grundlegender \u00c4nderungen im Vergleich zu den vergangenen 10, 20 Jahren. Mit dem Fonds- und Stiftungsexperten Frank Wettlauffer sprachen wir dar\u00fcber, was im Stiftungsverm\u00f6gen heute z\u00e4hlt\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/\" \/>\n<meta property=\"og:site_name\" content=\"Der Stiftungsblog f\u00fcr die Stiftungspraxis\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-10T07:45:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-08T12:30:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/07\/Podcast-AHOI-NPO-Folge-13-Stellschrauben-im-Stiftungsvermoegen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tobias Karow\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tobias Karow\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\\\/\"},\"author\":{\"name\":\"Tobias Karow\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/person\\\/3a42780bf87a2088578f1e8077ccfa44\"},\"headline\":\"Stellschrauben im Stiftungsverm\u00f6gen bitte jetzt drehen\",\"datePublished\":\"2020-07-10T07:45:11+00:00\",\"dateModified\":\"2021-10-08T12:30:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\\\/\"},\"wordCount\":98,\"publisher\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Podcast-AHOI-NPO-Folge-13-Stellschrauben-im-Stiftungsvermoegen.jpg\",\"keywords\":[\"Podcast\",\"Stiftungsverm\u00f6gen\",\"Niedrigzins\",\"FreitagsPodcast\",\"Stiftungsfonds\",\"Corona-Crash\",\"stiftungsgeeignete Fonds\"],\"articleSection\":[\"Stiftungsverm\u00f6gen &amp; Stiftungsfonds\",\"#stiftungenst\u00e4rken\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\\\/\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\\\/\",\"name\":\"Stellschrauben im Stiftungsverm\u00f6gen bitte jetzt drehen - Der Stiftungsblog f\u00fcr die Stiftungspraxis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Podcast-AHOI-NPO-Folge-13-Stellschrauben-im-Stiftungsvermoegen.jpg\",\"datePublished\":\"2020-07-10T07:45:11+00:00\",\"dateModified\":\"2021-10-08T12:30:37+00:00\",\"description\":\"Stiftungsverm\u00f6gen anzulegen, ganz gleich ob delegiert an Stiftungsfonds, in die H\u00e4nde von Verm\u00f6gensverwaltern gelegt oder selbst gemacht, bedarf heute ein paar ganz grundlegender \u00c4nderungen im Vergleich zu den vergangenen 10, 20 Jahren. Mit dem Fonds- und Stiftungsexperten Frank Wettlauffer sprachen wir dar\u00fcber, was im Stiftungsverm\u00f6gen heute z\u00e4hlt\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Podcast-AHOI-NPO-Folge-13-Stellschrauben-im-Stiftungsvermoegen.jpg\",\"contentUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Podcast-AHOI-NPO-Folge-13-Stellschrauben-im-Stiftungsvermoegen.jpg\",\"width\":1200,\"height\":675,\"caption\":\"Podcast AHOI NPO Folge 13 - Stellschrauben im Stiftungsverm\u00f6gen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stellschrauben im Stiftungsverm\u00f6gen bitte jetzt drehen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/\",\"name\":\"Der Stiftungsblog f\u00fcr die Stiftungspraxis\",\"description\":\"#stiftungenst\u00e4rken - NPO-Expertise von NPO-Experten\",\"publisher\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#organization\",\"name\":\"stiftungsmarktplatz.eu GbR\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Logo-blog-retina.png\",\"contentUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Logo-blog-retina.png\",\"width\":140,\"height\":130,\"caption\":\"stiftungsmarktplatz.eu GbR\"},\"image\":{\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/18563519\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQrF6RQRFGxTokVV4nbx25Q\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/#\\\/schema\\\/person\\\/3a42780bf87a2088578f1e8077ccfa44\",\"name\":\"Tobias Karow\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/tobias-karow-2024-150x150.png\",\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/tobias-karow-2024-150x150.png\",\"contentUrl\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/tobias-karow-2024-150x150.png\",\"caption\":\"Tobias Karow\"},\"description\":\"ist Gr\u00fcnder und Gesch\u00e4ftsf\u00fchrer von stiftungsmarktplatz.eu und im Stiftungswesen in Deutschland, \u00d6sterreich, der Schweiz und Liechtenstein seit 10 Jahren aktiv. Er ist Herausgeber der FondsFibel f\u00fcr Stiftungen &amp; NPOs, dem f\u00fchrenden Nachschlagewerk f\u00fcr Stiftungsfonds und stiftungsgeeignete Fonds (www.fondsfibel.de), Vortr\u00e4ge h\u00e4lt er vor allem zum Thema \u201aStiftungen und ihr Weg in die digitale Welt\u2018. F\u00fcr beide Themen betreibt er den Blog #stiftungenst\u00e4rken.\",\"sameAs\":[\"https:\\\/\\\/www.fondsfibel.de\"],\"url\":\"https:\\\/\\\/stiftungsmarktplatz.eu\\\/blog\\\/author\\\/tobias-karow\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stellschrauben im Stiftungsverm\u00f6gen bitte jetzt drehen - Der Stiftungsblog f\u00fcr die Stiftungspraxis","description":"Stiftungsverm\u00f6gen anzulegen, ganz gleich ob delegiert an Stiftungsfonds, in die H\u00e4nde von Verm\u00f6gensverwaltern gelegt oder selbst gemacht, bedarf heute ein paar ganz grundlegender \u00c4nderungen im Vergleich zu den vergangenen 10, 20 Jahren. Mit dem Fonds- und Stiftungsexperten Frank Wettlauffer sprachen wir dar\u00fcber, was im Stiftungsverm\u00f6gen heute z\u00e4hlt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/","og_locale":"de_DE","og_type":"article","og_title":"Stellschrauben im Stiftungsverm\u00f6gen bitte jetzt drehen - Der Stiftungsblog f\u00fcr die Stiftungspraxis","og_description":"Stiftungsverm\u00f6gen anzulegen, ganz gleich ob delegiert an Stiftungsfonds, in die H\u00e4nde von Verm\u00f6gensverwaltern gelegt oder selbst gemacht, bedarf heute ein paar ganz grundlegender \u00c4nderungen im Vergleich zu den vergangenen 10, 20 Jahren. Mit dem Fonds- und Stiftungsexperten Frank Wettlauffer sprachen wir dar\u00fcber, was im Stiftungsverm\u00f6gen heute z\u00e4hlt","og_url":"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/","og_site_name":"Der Stiftungsblog f\u00fcr die Stiftungspraxis","article_published_time":"2020-07-10T07:45:11+00:00","article_modified_time":"2021-10-08T12:30:37+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/07\/Podcast-AHOI-NPO-Folge-13-Stellschrauben-im-Stiftungsvermoegen.jpg","type":"image\/jpeg"}],"author":"Tobias Karow","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Tobias Karow","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/#article","isPartOf":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/"},"author":{"name":"Tobias Karow","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/person\/3a42780bf87a2088578f1e8077ccfa44"},"headline":"Stellschrauben im Stiftungsverm\u00f6gen bitte jetzt drehen","datePublished":"2020-07-10T07:45:11+00:00","dateModified":"2021-10-08T12:30:37+00:00","mainEntityOfPage":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/"},"wordCount":98,"publisher":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#organization"},"image":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/#primaryimage"},"thumbnailUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/07\/Podcast-AHOI-NPO-Folge-13-Stellschrauben-im-Stiftungsvermoegen.jpg","keywords":["Podcast","Stiftungsverm\u00f6gen","Niedrigzins","FreitagsPodcast","Stiftungsfonds","Corona-Crash","stiftungsgeeignete Fonds"],"articleSection":["Stiftungsverm\u00f6gen &amp; Stiftungsfonds","#stiftungenst\u00e4rken"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/","name":"Stellschrauben im Stiftungsverm\u00f6gen bitte jetzt drehen - Der Stiftungsblog f\u00fcr die Stiftungspraxis","isPartOf":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/#primaryimage"},"image":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/#primaryimage"},"thumbnailUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/07\/Podcast-AHOI-NPO-Folge-13-Stellschrauben-im-Stiftungsvermoegen.jpg","datePublished":"2020-07-10T07:45:11+00:00","dateModified":"2021-10-08T12:30:37+00:00","description":"Stiftungsverm\u00f6gen anzulegen, ganz gleich ob delegiert an Stiftungsfonds, in die H\u00e4nde von Verm\u00f6gensverwaltern gelegt oder selbst gemacht, bedarf heute ein paar ganz grundlegender \u00c4nderungen im Vergleich zu den vergangenen 10, 20 Jahren. Mit dem Fonds- und Stiftungsexperten Frank Wettlauffer sprachen wir dar\u00fcber, was im Stiftungsverm\u00f6gen heute z\u00e4hlt","breadcrumb":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/#primaryimage","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/07\/Podcast-AHOI-NPO-Folge-13-Stellschrauben-im-Stiftungsvermoegen.jpg","contentUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/07\/Podcast-AHOI-NPO-Folge-13-Stellschrauben-im-Stiftungsvermoegen.jpg","width":1200,"height":675,"caption":"Podcast AHOI NPO Folge 13 - Stellschrauben im Stiftungsverm\u00f6gen"},{"@type":"BreadcrumbList","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/stellschrauben-im-stiftungsvermoegen-bitte-jetzt-drehen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/stiftungsmarktplatz.eu\/blog\/"},{"@type":"ListItem","position":2,"name":"Stellschrauben im Stiftungsverm\u00f6gen bitte jetzt drehen"}]},{"@type":"WebSite","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#website","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/","name":"Der Stiftungsblog f\u00fcr die Stiftungspraxis","description":"#stiftungenst\u00e4rken - NPO-Expertise von NPO-Experten","publisher":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stiftungsmarktplatz.eu\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#organization","name":"stiftungsmarktplatz.eu GbR","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/03\/Logo-blog-retina.png","contentUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2020\/03\/Logo-blog-retina.png","width":140,"height":130,"caption":"stiftungsmarktplatz.eu GbR"},"image":{"@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/18563519\/","https:\/\/www.youtube.com\/channel\/UCQrF6RQRFGxTokVV4nbx25Q"]},{"@type":"Person","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/#\/schema\/person\/3a42780bf87a2088578f1e8077ccfa44","name":"Tobias Karow","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/05\/tobias-karow-2024-150x150.png","url":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/05\/tobias-karow-2024-150x150.png","contentUrl":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-content\/uploads\/2024\/05\/tobias-karow-2024-150x150.png","caption":"Tobias Karow"},"description":"ist Gr\u00fcnder und Gesch\u00e4ftsf\u00fchrer von stiftungsmarktplatz.eu und im Stiftungswesen in Deutschland, \u00d6sterreich, der Schweiz und Liechtenstein seit 10 Jahren aktiv. Er ist Herausgeber der FondsFibel f\u00fcr Stiftungen &amp; NPOs, dem f\u00fchrenden Nachschlagewerk f\u00fcr Stiftungsfonds und stiftungsgeeignete Fonds (www.fondsfibel.de), Vortr\u00e4ge h\u00e4lt er vor allem zum Thema \u201aStiftungen und ihr Weg in die digitale Welt\u2018. F\u00fcr beide Themen betreibt er den Blog #stiftungenst\u00e4rken.","sameAs":["https:\/\/www.fondsfibel.de"],"url":"https:\/\/stiftungsmarktplatz.eu\/blog\/author\/tobias-karow\/"}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts\/1317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/comments?post=1317"}],"version-history":[{"count":6,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts\/1317\/revisions"}],"predecessor-version":[{"id":2729,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/posts\/1317\/revisions\/2729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/media\/1322"}],"wp:attachment":[{"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/media?parent=1317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/categories?post=1317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stiftungsmarktplatz.eu\/blog\/wp-json\/wp\/v2\/tags?post=1317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}